{"id":17868,"date":"2022-08-03T14:49:24","date_gmt":"2022-08-03T14:49:24","guid":{"rendered":"https:\/\/harpalindia.com\/version1\/?page_id=17868"},"modified":"2022-08-25T13:13:13","modified_gmt":"2022-08-25T13:13:13","slug":"portfolio-metro-slide-in-left","status":"publish","type":"page","link":"https:\/\/harpalindia.com\/version1\/portfolio-metro-slide-in-left\/","title":{"rendered":"Portfolio Metro Slide In Left"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"17868\" class=\"elementor elementor-17868\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-0be8c2a elementor-section-boxed elementor-section-height-default elementor-section-height-default sc_fly_static\" data-id=\"0be8c2a\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-extended\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-84dd8c2 sc_inner_width_none sc_content_align_inherit sc_layouts_column_icons_position_left sc_fly_static\" data-id=\"84dd8c2\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c8f479c sc_style_default sc_fly_static elementor-widget elementor-widget-trx_sc_blogger\" data-id=\"c8f479c\" data-element_type=\"widget\" data-widget_type=\"trx_sc_blogger.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div \t\tclass=\"sc_blogger sc_blogger_lay_portfolio_grid sc_blogger_lay_portfolio_grid_grid_style_5 sc_item_filters_tabs_none alignnone\" ><div class=\"sc_blogger_content sc_item_content sc_item_posts_container\" ><div class=\"sc_blogger_grid_wrap sc_blogger_grid_4\" ><div data-post-id=\"2737\" data-item-number=\"1\" class=\"sc_blogger_item sc_item_container post_container sc_blogger_item_lay_portfolio sc_blogger_item_lay_portfolio_style_5 sc_blogger_item_odd sc_blogger_item_align_none post_format_standard sc_blogger_item_with_image sc_blogger_item_no_excerpt sc_blogger_item_image_position_top post-2737 cpt_portfolio type-cpt_portfolio status-publish has-post-thumbnail hentry cpt_portfolio_group-mens-fashion\" ><div class=\"sc_blogger_item_body\"><div class=\"post_featured with_thumb hover_link sc_item_featured sc_blogger_item_featured post_featured_bg\" data-ratio=\"16:9\"><span class=\"post_thumb post_thumb_bg bg_in fabric_inline_2080542509\"><\/span>\t\t\t\t\t\t<div class=\"mask\"><\/div>\n\t\t\t\t\t\t<div class=\"post_info_bl\"><h5 class=\"sc_blogger_item_title entry-title\" data-item-number=\"1\"><a href=\"https:\/\/harpalindia.com\/version1\/portfolio\/mens-fashion\/\" rel=\"bookmark\">Men&#8217;s Fashion<\/a><\/h5><div class=\"post_meta sc_blogger_item_meta post_meta_categories\"><span class=\"post_meta_item post_categories cat_sep\"><a href=\"https:\/\/harpalindia.com\/version1\/portfolio_group\/mens-fashion\/\" title=\"View all posts in Men's Fashion\">Men's Fashion<\/a><\/span><\/div><\/div><a class=\"post_link sc_blogger_item_link\" href=\"https:\/\/harpalindia.com\/version1\/portfolio\/mens-fashion\/\"><\/a>\t\t\t<a href=\"https:\/\/harpalindia.com\/version1\/portfolio\/mens-fashion\/\"  aria-hidden=\"true\" class=\"link\"><\/a>\n\t\t\t<\/div><\/div><!-- .sc_blogger_item_body --><\/div><!-- .sc_blogger_item --><div data-post-id=\"2756\" data-item-number=\"2\" class=\"sc_blogger_item sc_item_container post_container sc_blogger_item_lay_portfolio sc_blogger_item_lay_portfolio_style_5 sc_blogger_item_even sc_blogger_item_align_none post_format_standard sc_blogger_item_with_image sc_blogger_item_no_excerpt sc_blogger_item_image_position_top post-2756 cpt_portfolio type-cpt_portfolio status-publish has-post-thumbnail hentry cpt_portfolio_group-mens-fashion\" ><div class=\"sc_blogger_item_body\"><div class=\"post_featured with_thumb hover_link sc_item_featured sc_blogger_item_featured post_featured_bg\" data-ratio=\"16:9\"><span class=\"post_thumb post_thumb_bg bg_in fabric_inline_1159204090\"><\/span>\t\t\t\t\t\t<div class=\"mask\"><\/div>\n\t\t\t\t\t\t<div class=\"post_info_bl\"><h5 class=\"sc_blogger_item_title entry-title\" data-item-number=\"2\"><a href=\"https:\/\/harpalindia.com\/version1\/portfolio\/color-trends\/\" rel=\"bookmark\">Color Trends<\/a><\/h5><div class=\"post_meta sc_blogger_item_meta post_meta_categories\"><span class=\"post_meta_item post_categories cat_sep\"><a href=\"https:\/\/harpalindia.com\/version1\/portfolio_group\/mens-fashion\/\" title=\"View all posts in Men's Fashion\">Men's Fashion<\/a><\/span><\/div><\/div><a class=\"post_link sc_blogger_item_link\" href=\"https:\/\/harpalindia.com\/version1\/portfolio\/color-trends\/\"><\/a>\t\t\t<a href=\"https:\/\/harpalindia.com\/version1\/portfolio\/color-trends\/\"  aria-hidden=\"true\" class=\"link\"><\/a>\n\t\t\t<\/div><\/div><!-- .sc_blogger_item_body --><\/div><!-- .sc_blogger_item --><div data-post-id=\"2759\" data-item-number=\"3\" class=\"sc_blogger_item sc_item_container post_container sc_blogger_item_lay_portfolio sc_blogger_item_lay_portfolio_style_5 sc_blogger_item_odd sc_blogger_item_align_none post_format_standard sc_blogger_item_with_image sc_blogger_item_no_excerpt sc_blogger_item_image_position_top post-2759 cpt_portfolio type-cpt_portfolio status-publish has-post-thumbnail hentry cpt_portfolio_group-mens-fashion\" ><div class=\"sc_blogger_item_body\"><div class=\"post_featured with_thumb hover_link sc_item_featured sc_blogger_item_featured post_featured_bg\" data-ratio=\"16:9\"><span class=\"post_thumb post_thumb_bg bg_in fabric_inline_1800046077\"><\/span>\t\t\t\t\t\t<div class=\"mask\"><\/div>\n\t\t\t\t\t\t<div class=\"post_info_bl\"><h5 class=\"sc_blogger_item_title entry-title\" data-item-number=\"3\"><a href=\"https:\/\/harpalindia.com\/version1\/portfolio\/special-events\/\" rel=\"bookmark\">Special Events<\/a><\/h5><div class=\"post_meta sc_blogger_item_meta post_meta_categories\"><span class=\"post_meta_item post_categories cat_sep\"><a href=\"https:\/\/harpalindia.com\/version1\/portfolio_group\/mens-fashion\/\" title=\"View all posts in Men's Fashion\">Men's Fashion<\/a><\/span><\/div><\/div><a class=\"post_link sc_blogger_item_link\" href=\"https:\/\/harpalindia.com\/version1\/portfolio\/special-events\/\"><\/a>\t\t\t<a href=\"https:\/\/harpalindia.com\/version1\/portfolio\/special-events\/\"  aria-hidden=\"true\" class=\"link\"><\/a>\n\t\t\t<\/div><\/div><!-- .sc_blogger_item_body --><\/div><!-- .sc_blogger_item --><div data-post-id=\"2761\" data-item-number=\"4\" class=\"sc_blogger_item sc_item_container post_container sc_blogger_item_lay_portfolio sc_blogger_item_lay_portfolio_style_5 sc_blogger_item_even sc_blogger_item_align_none post_format_standard sc_blogger_item_with_image sc_blogger_item_no_excerpt sc_blogger_item_image_position_top post-2761 cpt_portfolio type-cpt_portfolio status-publish has-post-thumbnail hentry cpt_portfolio_group-mens-fashion\" ><div class=\"sc_blogger_item_body\"><div class=\"post_featured with_thumb hover_link sc_item_featured sc_blogger_item_featured post_featured_bg\" data-ratio=\"16:9\"><span class=\"post_thumb post_thumb_bg bg_in fabric_inline_1865391144\"><\/span>\t\t\t\t\t\t<div class=\"mask\"><\/div>\n\t\t\t\t\t\t<div class=\"post_info_bl\"><h5 class=\"sc_blogger_item_title entry-title\" data-item-number=\"4\"><a href=\"https:\/\/harpalindia.com\/version1\/portfolio\/business-style\/\" rel=\"bookmark\">Business Style<\/a><\/h5><div class=\"post_meta sc_blogger_item_meta post_meta_categories\"><span class=\"post_meta_item post_categories cat_sep\"><a href=\"https:\/\/harpalindia.com\/version1\/portfolio_group\/mens-fashion\/\" title=\"View all posts in Men's Fashion\">Men's Fashion<\/a><\/span><\/div><\/div><a class=\"post_link sc_blogger_item_link\" href=\"https:\/\/harpalindia.com\/version1\/portfolio\/business-style\/\"><\/a>\t\t\t<a href=\"https:\/\/harpalindia.com\/version1\/portfolio\/business-style\/\"  aria-hidden=\"true\" class=\"link\"><\/a>\n\t\t\t<\/div><\/div><!-- .sc_blogger_item_body --><\/div><!-- .sc_blogger_item --><\/div><\/div><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Men&#8217;s Fashion Men&#8217;s Fashion Color Trends Men&#8217;s Fashion Special Events Men&#8217;s Fashion Business Style Men&#8217;s Fashion<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-17868","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/harpalindia.com\/version1\/wp-json\/wp\/v2\/pages\/17868","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/harpalindia.com\/version1\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/harpalindia.com\/version1\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/harpalindia.com\/version1\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/harpalindia.com\/version1\/wp-json\/wp\/v2\/comments?post=17868"}],"version-history":[{"count":0,"href":"https:\/\/harpalindia.com\/version1\/wp-json\/wp\/v2\/pages\/17868\/revisions"}],"wp:attachment":[{"href":"https:\/\/harpalindia.com\/version1\/wp-json\/wp\/v2\/media?parent=17868"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}