{"id":17886,"date":"2022-08-03T15:12:58","date_gmt":"2022-08-03T15:12:58","guid":{"rendered":"https:\/\/harpalindia.com\/version1\/?post_type=cpt_portfolio&#038;p=17886"},"modified":"2022-10-17T14:19:32","modified_gmt":"2022-10-17T14:19:32","slug":"home-textile","status":"publish","type":"cpt_portfolio","link":"https:\/\/harpalindia.com\/version1\/portfolio\/home-textile\/","title":{"rendered":"Home Textile"},"content":{"rendered":"\n<h3 class=\"wp-block-heading\">Modern Brand Book<\/h3>\n\n\n\n<p>Dicta sunt explicabo. Nemo enim ipsam voluptatem quia voluptas sit aspernatur aut odit aut fugit, quia. Dicta sunt explicabo. Adipiscing elit, sed do eiusmod tempor incididunt ut labore et dolore magna aliqua. Ut enim minim veniam quis nostrud exercitation ipsam voluptatem. <\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-2 is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"683\" data-id=\"17863\" src=\"https:\/\/harpalindia.com\/version1\/wp-content\/uploads\/2020\/05\/portfolio-image2-1024x683.jpg\" alt=\"\" class=\"wp-image-17863\" srcset=\"https:\/\/harpalindia.com\/version1\/wp-content\/uploads\/2020\/05\/portfolio-image2-1024x683.jpg 1024w, https:\/\/harpalindia.com\/version1\/wp-content\/uploads\/2020\/05\/portfolio-image2-600x400.jpg 600w, https:\/\/harpalindia.com\/version1\/wp-content\/uploads\/2020\/05\/portfolio-image2-300x200.jpg 300w, https:\/\/harpalindia.com\/version1\/wp-content\/uploads\/2020\/05\/portfolio-image2-768x512.jpg 768w, https:\/\/harpalindia.com\/version1\/wp-content\/uploads\/2020\/05\/portfolio-image2-1536x1024.jpg 1536w, https:\/\/harpalindia.com\/version1\/wp-content\/uploads\/2020\/05\/portfolio-image2-370x247.jpg 370w, https:\/\/harpalindia.com\/version1\/wp-content\/uploads\/2020\/05\/portfolio-image2-840x560.jpg 840w, https:\/\/harpalindia.com\/version1\/wp-content\/uploads\/2020\/05\/portfolio-image2-410x273.jpg 410w, https:\/\/harpalindia.com\/version1\/wp-content\/uploads\/2020\/05\/portfolio-image2.jpg 1920w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"683\" data-id=\"17864\" src=\"https:\/\/harpalindia.com\/version1\/wp-content\/uploads\/2020\/05\/portfolio-image3-1024x683.jpg\" alt=\"\" class=\"wp-image-17864\" srcset=\"https:\/\/harpalindia.com\/version1\/wp-content\/uploads\/2020\/05\/portfolio-image3-1024x683.jpg 1024w, https:\/\/harpalindia.com\/version1\/wp-content\/uploads\/2020\/05\/portfolio-image3-600x400.jpg 600w, https:\/\/harpalindia.com\/version1\/wp-content\/uploads\/2020\/05\/portfolio-image3-300x200.jpg 300w, https:\/\/harpalindia.com\/version1\/wp-content\/uploads\/2020\/05\/portfolio-image3-768x512.jpg 768w, https:\/\/harpalindia.com\/version1\/wp-content\/uploads\/2020\/05\/portfolio-image3-1536x1024.jpg 1536w, https:\/\/harpalindia.com\/version1\/wp-content\/uploads\/2020\/05\/portfolio-image3-370x247.jpg 370w, https:\/\/harpalindia.com\/version1\/wp-content\/uploads\/2020\/05\/portfolio-image3-840x560.jpg 840w, https:\/\/harpalindia.com\/version1\/wp-content\/uploads\/2020\/05\/portfolio-image3-410x273.jpg 410w, https:\/\/harpalindia.com\/version1\/wp-content\/uploads\/2020\/05\/portfolio-image3.jpg 1920w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"523\" data-id=\"18476\" src=\"https:\/\/harpalindia.com\/version1\/wp-content\/uploads\/2022\/08\/tailor-header-1024x523.jpg\" alt=\"\" class=\"wp-image-18476\" srcset=\"https:\/\/harpalindia.com\/version1\/wp-content\/uploads\/2022\/08\/tailor-header-1024x523.jpg 1024w, https:\/\/harpalindia.com\/version1\/wp-content\/uploads\/2022\/08\/tailor-header-600x306.jpg 600w, https:\/\/harpalindia.com\/version1\/wp-content\/uploads\/2022\/08\/tailor-header-300x153.jpg 300w, https:\/\/harpalindia.com\/version1\/wp-content\/uploads\/2022\/08\/tailor-header-768x392.jpg 768w, https:\/\/harpalindia.com\/version1\/wp-content\/uploads\/2022\/08\/tailor-header-1536x784.jpg 1536w, https:\/\/harpalindia.com\/version1\/wp-content\/uploads\/2022\/08\/tailor-header-370x189.jpg 370w, https:\/\/harpalindia.com\/version1\/wp-content\/uploads\/2022\/08\/tailor-header-840x429.jpg 840w, https:\/\/harpalindia.com\/version1\/wp-content\/uploads\/2022\/08\/tailor-header-410x209.jpg 410w, https:\/\/harpalindia.com\/version1\/wp-content\/uploads\/2022\/08\/tailor-header.jpg 1920w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Dicta sunt explicabo. Nemo ipsam voluptatem quia voluptas aspernatur aut odit aut fugit, sed quia. Dicta sunt explicabo. Nemo enim ipsam voluptatem quia voluptas sit aspernatur aut odit.<\/p>\n","protected":false},"author":1,"featured_media":17887,"comment_status":"closed","ping_status":"closed","template":"","cpt_portfolio_group":[195],"class_list":["post-17886","cpt_portfolio","type-cpt_portfolio","status-publish","has-post-thumbnail","hentry","cpt_portfolio_group-craft-decor"],"_links":{"self":[{"href":"https:\/\/harpalindia.com\/version1\/wp-json\/wp\/v2\/cpt_portfolio\/17886","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/harpalindia.com\/version1\/wp-json\/wp\/v2\/cpt_portfolio"}],"about":[{"href":"https:\/\/harpalindia.com\/version1\/wp-json\/wp\/v2\/types\/cpt_portfolio"}],"author":[{"embeddable":true,"href":"https:\/\/harpalindia.com\/version1\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/harpalindia.com\/version1\/wp-json\/wp\/v2\/comments?post=17886"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/harpalindia.com\/version1\/wp-json\/wp\/v2\/media\/17887"}],"wp:attachment":[{"href":"https:\/\/harpalindia.com\/version1\/wp-json\/wp\/v2\/media?parent=17886"}],"wp:term":[{"taxonomy":"cpt_portfolio_group","embeddable":true,"href":"https:\/\/harpalindia.com\/version1\/wp-json\/wp\/v2\/cpt_portfolio_group?post=17886"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}